{"id":10351,"date":"2023-11-17T21:12:53","date_gmt":"2023-11-17T21:12:53","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=10351"},"modified":"2023-11-17T21:13:05","modified_gmt":"2023-11-17T21:13:05","slug":"a-escondidas-entrega-secretaria-paquete-hacendario-2024-por-68-mil-mdp-8-6-mas-que-este-ano","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/a-escondidas-entrega-secretaria-paquete-hacendario-2024-por-68-mil-mdp-8-6-mas-que-este-ano\/politica\/","title":{"rendered":"A escondidas, entrega secretar\u00eda Paquete Hacendario 2024 por 68 mil mdp; 8.6% m\u00e1s que este a\u00f1o"},"content":{"rendered":"\n<p><strong>Sin convocatoria a medios de comunicaci\u00f3n, la secretaria de Hacienda de Hidalgo, Mar\u00eda Esther Ram\u00edrez Vargas<\/strong>, present\u00f3 este viernes al Congreso local el Paquete Hacendario 2024 por 68 mil 82 millones 300 903 pesos de pesos, 8.6 por ciento mayor respecto al del ejercicio fiscal 2023.<\/p>\n\n\n\n<p>Ante los diputados de la Comisi\u00f3n Permanente de Hacienda y Presupuesto, la funcionaria estatal present\u00f3 la iniciativa de Ley de Ingresos la el proyecto de decreto de Presupuesto de Egresos, as\u00ed como as\u00ed como la Miscel\u00e1nea Fiscal para el siguiente a\u00f1o.<\/p>\n\n\n\n<p>Ram\u00edrez Vargas afirm\u00f3 que la propuesta \u201ccumple con el compromiso\u201d de no incrementar ni crear nuevos impuestos.<\/p>\n\n\n\n<p><strong>En el rubro recursos propios, se considera un crecimiento \u201chist\u00f3rico\u201d superior a 34 por ciento respecto al ejercicio fiscal 2023, al pasar de 5 mil 35 millones 417 mil 790 pesos a 6 mil 756 millones 909 mil 234 pesos para 2024<\/strong>, \u201cresultado de un esquema tributario eficiente y de la implementaci\u00f3n de pol\u00edticas fiscales acordes con la realidad econ\u00f3mica\u201d, presumi\u00f3.<\/p>\n\n\n\n<p>Ello representa el 9,9 por ciento del total del presupuesto que se propone a consideraci\u00f3n del Congreso local, que deber ser analizado y en su caso aprobado el 22 de diciembre.<\/p>\n\n\n\n<p>A\u00f1adi\u00f3 que no se tiene contemplada la contrataci\u00f3n de deuda p\u00fablica durante el siguiente a\u00f1o.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La funcionaria indic\u00f3 que el gasto de inversi\u00f3n para 2024 se estima en 9 mil 200 millones de pesos, lo que representa un 20 por ciento m\u00e1s que en 2023.<br><br>Esto permitir\u00e1 destinar recursos para el fortalecimiento de la infraestructura f\u00edsica en los 84 municipios (\u2026) ser\u00e1 una gran oportunidad al fortalecimiento de la infraestructura p\u00fablica y dar continuidad a los programas sociales,\u201d, expuso.<\/p><\/blockquote><\/figure>\n\n\n\n<p>Asever\u00f3 que de los 3 mil 100 millones de pesos para programas sociales, a los de atenci\u00f3n al bienestar se destinar\u00e1n mil 900 millones de pesos para grupos vulnerables: ni\u00f1as, ni\u00f1os y adolescentes j\u00f3venes y adultos mayores mujeres, pueblos ind\u00edgenas, personas con discapacidad y personas de la diversidad sexual y de g\u00e9nero, as\u00ed como migrantes y poblaci\u00f3n en situaci\u00f3n de pobreza.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u201cEsto nos permitir\u00e1 mantener y ampliar la cobertura en programas como \u00fatiles uniformes escolares, libros de texto becas, bienestar y desarrollo para personas y situaci\u00f3n de vulnerabilidad, madres solteras, Transformando con la Juventud, Tu Experiencia Transforma, Mujer Rural, Construye tu Camino, as\u00ed como los distintos programas de apoyo al campo\u201d, expuso.<br><br><br>SALUD Y EDUCACI\u00d3N, CON LA MAYOR TAJADA<br><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Por rubros, la funcionaria indic\u00f3 que educaci\u00f3n considera la mayor parte del presupuesto, con 29 mil millones de pesos; salud, con 5 mil millones 800; infraestructura, con 5 mil 200 millones de pesos, y seguridad, 3 mil millones de pesos.<br><br>Respecto al fortalecimiento de la infraestructura, no hay duda que es la base para el desarrollo y crecimiento de la entidad, por ello se contempla una inversi\u00f3n superior a los 5 mi 200 millones de pesos, 7.2 por ciento m\u00e1s que en 2023, estos recursos permitir\u00e1n continuar la rehabilitaci\u00f3n modernizaci\u00f3n y construcci\u00f3n de carreteras, caminos rurales l\u00edneas de conducci\u00f3n de agua potable, drenaje saneamiento, infraestructura educativa, recuperaci\u00f3n de espacios espacios p\u00fablicos, entre otros\u201d, expuso.<\/p><\/blockquote><\/figure>\n\n\n\n<p>Dijo que entre los ramos con mayor fortalecimiento presupuestario para 2024 se encuentra medio ambiente, a trav\u00e9s de programas y proyectos con el objetivo de preservar y mejorar el entorno y el ecosistema. Para ello se destinar\u00e1n m\u00e1s de 304 millones de pesos, 163 millones de pesos m\u00e1s que este a\u00f1o.<\/p>\n\n\n\n<p><strong>Dijo el ramo de desarrollo econ\u00f3mico es el segundo con mayor crecimiento, al pasar de 268 millones a m\u00e1s de 539 millones de pesos para 2024.<\/strong><br><br>En su presentaci\u00f3n, la funcionaria estatal no dio cuenta de la iniciativa de presupuesto para los otros poderes del estado ni de los \u00f3rganos aut\u00f3nomos, tampoco del recurso que se prev\u00e9n para los 84 municipios.<br><\/p>\n\n\n\n<p>Tras finalizar su presentaci\u00f3n, la secretaria de Haciendo baj\u00f3 por el elevador privado de cuarto piso de la Torre Legislativa, que se encuentra en la presidencia de la Junta de Gobierno, para evadir los cuestionamientos sobre el Paquete Hacendario por parte de los medios de comunicaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sin convocatoria a medios de comunicaci\u00f3n, la secretaria de Hacienda de Hidalgo, Mar\u00eda Esther Ram\u00edrez Vargas, present\u00f3 este viernes al Congreso local el Paquete Hacendario 2024 por 68 mil 82&hellip; <\/p>\n","protected":false},"author":4,"featured_media":10352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/10351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=10351"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/10351\/revisions"}],"predecessor-version":[{"id":10353,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/10351\/revisions\/10353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/10352"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=10351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=10351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=10351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}