{"id":10521,"date":"2023-11-24T20:44:08","date_gmt":"2023-11-24T20:44:08","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=10521"},"modified":"2023-11-24T20:44:11","modified_gmt":"2023-11-24T20:44:11","slug":"advierten-que-locatario-de-mercado-barreteros-busca-tirar-muro-del-inmueble-protegido-por-valor-cultural","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/advierten-que-locatario-de-mercado-barreteros-busca-tirar-muro-del-inmueble-protegido-por-valor-cultural\/reportajes_especiales\/","title":{"rendered":"Advierten que locatario de mercado Barreteros busca tirar muro del inmueble protegido por valor cultural"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><strong>Locatarios del mercado Barreteros advirtieron que uno de los comerciantes de carnicer\u00eda pretende derribar un muro dentro del inmueble para conectar dos establecimientos, pese a que es un monumento art\u00edstico con valor cultural protegido, el cual data de 1927.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/revistaacropolis.com\/wp-content\/uploads\/2023\/11\/0ee4c055-6bdb-464f-bb27-412b89d50a1c.jpeg\" alt=\"\" class=\"wp-image-10524\" srcset=\"https:\/\/revistaacropolis.com\/wp-content\/uploads\/2023\/11\/0ee4c055-6bdb-464f-bb27-412b89d50a1c.jpeg 1024w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2023\/11\/0ee4c055-6bdb-464f-bb27-412b89d50a1c-300x200.jpeg 300w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2023\/11\/0ee4c055-6bdb-464f-bb27-412b89d50a1c-768x512.jpeg 768w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2023\/11\/0ee4c055-6bdb-464f-bb27-412b89d50a1c-600x400.jpeg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Demetrio Vargas Garnica, uno de los vendedores en el inmueble en la calle de Guerrero, en el Centro Hist\u00f3rico de Pachuca, se\u00f1al\u00f3 que el locatario con seis a\u00f1os de antig\u00fcedad busca tirar una de las paredes, lo que podr\u00eda en riesgo de estabilidad de la estructura que est\u00e1 hecha solo de ladrillo y no cuenta con trabes o columnas de acero.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>De por s\u00ed esta fracturado (el mercado), imag\u00ednese que tumbe un muro de m\u00e1s de 50 cent\u00edmetros, entonces pueden fracturar bastante el mercado; adem\u00e1s, donde va a abrir, ah\u00ed cae una columna de acero de parte del techo. Estamos preocupados por esa situaci\u00f3n y por eso nos oponemos rotundamente a que abra ese muro\u201d, expres\u00f3.<\/p><\/blockquote><\/figure>\n\n\n\n<p>El comerciante que pretende conectar una carnicer\u00eda con un local que se encuentra en el la fachada izquierda -a\u00f1adi\u00f3- dice contar con un permiso otorgado por la Direcci\u00f3n de Comercio y Abasto del municipio y uno supuestamente dado por el Instituto Nacional de Antropolog\u00eda e Historia (INAH).<\/p>\n\n\n\n<p>\u201cHasta ahora no ha abierto, pero ya est\u00e1 puesto el marco para poder abrir, por eso, antes de, hay que evitar problemas y situaciones\u201d, explic\u00f3 el tambi\u00e9n carnicero con m\u00e1s de 50 a\u00f1os en el Barreteros.<\/p>\n\n\n\n<p>Agreg\u00f3 que el locatario se\u00f1alado no se presta para el di\u00e1logo y \u201cque se la saca\u201d diciendo que los dem\u00e1s comerciantes que se oponen a que haga una abertura le \u201ctiene envidia\u201d.<\/p>\n\n\n\n<p><strong>Afirm\u00f3 que hay 126 locatarios y que m\u00e1s de la mitad est\u00e1n en desacuerdo con intervenir el muro, pues insisti\u00f3 en que se corre el riesgo de \u201cque se caiga el mercado\u201d.<\/strong><\/p>\n\n\n\n<p>Marco Antonio Diaz Cortez, integrante del Comit\u00e9 del Centro Hist\u00f3rico de Pachuca, agreg\u00f3 que el mercado casi centenario era una plaza de comercio e intercambio, por lo que en la \u00e9poca postrevolucionaria se cre\u00f3 la obra.<\/p>\n\n\n\n<p>\u201cEs una obra ecl\u00e9ctica, la construye el ingeniero Abel Baladez, el mismo que construye la torre del Polit\u00e9cnico, a un lado de la universidad, que pertenece al Centro Cultural la Garza. Est\u00e1 hecha con piedra similar a la del Reloj (Monumental), la cantera de Tezoantla, que se le llama (\u2026) es uno de los mercados mejores ventilados\u201d, explic\u00f3.<\/p>\n\n\n\n<p>Indic\u00f3 que al inmueble solo se le da mantenimiento, pues dijo que funciona \u201cmuy bien\u201d a casi 100 a\u00f1os de su edificaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/revistaacropolis.com\/wp-content\/uploads\/2023\/11\/230b5cdd-bf4d-46fe-b5c4-7962eb3ea05a.jpeg\" alt=\"\" class=\"wp-image-10523\" srcset=\"https:\/\/revistaacropolis.com\/wp-content\/uploads\/2023\/11\/230b5cdd-bf4d-46fe-b5c4-7962eb3ea05a.jpeg 1024w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2023\/11\/230b5cdd-bf4d-46fe-b5c4-7962eb3ea05a-300x200.jpeg 300w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2023\/11\/230b5cdd-bf4d-46fe-b5c4-7962eb3ea05a-768x512.jpeg 768w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2023\/11\/230b5cdd-bf4d-46fe-b5c4-7962eb3ea05a-600x400.jpeg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Por ellos se busca que no sea alterada su estructura y cuidar la seguridad de las personas que lo frecuentan.<\/p>\n\n\n\n<p>\u201cLa estructura se tiene que mantener lo m\u00e1s \u00edntegra posible por una cuesti\u00f3n de seguridad tambi\u00e9n y, sobre todo, por una cuesti\u00f3n de patrimonio\u201d, expuso.<\/p>\n\n\n\n<p>Sobre el permiso que, acusan, otorg\u00f3 el ayuntamiento para el derribe de la pared, Diaz Cortez asegur\u00f3 que en Hidalgo el Centro INAH es el facultado para determinar si se pueden hace este tipo de intervenciones.<\/p>\n\n\n\n<p>\u201cParece muy sencilla una puerta, pero no lo es cuando se requiere de tratar un elemento art\u00edstico o un elemento hist\u00f3rico, a a veces se puede complicar mucho, y reitero, es un tema de seguridad\u201d, expuso.<\/p>\n\n\n\n<p>Agreg\u00f3 que se deben considerar temas de est\u00e9tica y protecci\u00f3n civil para poder intervenir un edificio de este tipo.<\/p>\n\n\n\n<p>\u201cImag\u00ednase al Reloj, que de repente tambi\u00e9n le haga un puerta extra o una situaci\u00f3n de esa naturaleza, pues obviamente ser\u00eda da\u00f1ino\u201d, expuso arquitecto.<\/p>\n\n\n\n<p>Record\u00f3 que hay una ficha de registro (I-0011401959) del mercado Barreteros que lo cataloga como un bien inmueble con valor cultural, por lo que la autoridades federales deben vigilarlo y dar cualquier tipo de permiso para su intervenci\u00f3n antes que el gobierno local.<\/p>\n\n\n\n<p>Vargas Garnica insisti\u00f3 en que desconocen si existe alg\u00fan tipo de permiso federal, pero dijo que el propietario de la concesi\u00f3n del establecimiento que busca derrumbar el muro present\u00f3 un documento \u201cque supuestamente les firm\u00f3 el anterior representen del INAH\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">DatoAcro<\/h3>\n\n\n\n<p>-Los quejosos enviaran un escrito a las autoridades municipales, estatal y federales.<\/p>\n\n\n\n<p>-Indicaron que el inmueble tiene tres fracturas estructurales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Locatarios del mercado Barreteros advirtieron que uno de los comerciantes de carnicer\u00eda pretende derribar un muro dentro del inmueble para conectar dos establecimientos, pese a que es un monumento art\u00edstico&hellip; <\/p>\n","protected":false},"author":4,"featured_media":10522,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[54],"tags":[],"class_list":["post-10521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reportajes_especiales"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/10521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=10521"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/10521\/revisions"}],"predecessor-version":[{"id":10525,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/10521\/revisions\/10525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/10522"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=10521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=10521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=10521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}