{"id":10780,"date":"2023-12-06T02:14:06","date_gmt":"2023-12-06T02:14:06","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=10780"},"modified":"2023-12-06T02:14:18","modified_gmt":"2023-12-06T02:14:18","slug":"dan-de-baja-de-padron-a-proveedores-favoritos-de-espectaculo-con-omar-fayad","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/dan-de-baja-de-padron-a-proveedores-favoritos-de-espectaculo-con-omar-fayad\/politica\/","title":{"rendered":"Dan de baja de padr\u00f3n a proveedores \u201cfavoritos\u201d de espect\u00e1culo con Omar Fayad"},"content":{"rendered":"\n<p><strong>Dos empresas vinculadas con la adjudicaci\u00f3n de licitaciones para la realizaci\u00f3n de espect\u00e1culos, eventos y hasta la compra insumos y medicamentos para la emergencia del Covid-19 en el gobierno de Omar Fayad Meneses fueron dadas de baja del registro del padr\u00f3n de proveedores del gobierno de Hidalgo por los pr\u00f3ximos 5 a\u00f1os: Creaciones, Espect\u00e1culos y Producciones de M\u00e9xico y Producciones Autica.<\/strong><\/p>\n\n\n\n<p>Por medio de una publicaci\u00f3n en el Peri\u00f3dico Oficial del Estado de Hidalgo (POEH), a trav\u00e9s de la Circular 008, la Contralor\u00eda de la entidad emiti\u00f3 una nueva lista de empresas sancionadas y con v\u00ednculos en licitaciones irregulares durante la pasada administraci\u00f3n, como parte de las investigaciones por diversos casos de corrupci\u00f3n.<\/p>\n\n\n\n<p><strong>Creaciones, Espect\u00e1culos y Producciones de M\u00e9xico y Producciones Autica tienen una relaci\u00f3n previa con m\u00faltiples contratos con el gobierno de Fayad Meneses<\/strong>, a trav\u00e9s de adjudicaciones en su momento por la Oficial\u00eda Mayor de la entidad.<\/p>\n\n\n\n<p>A ambas empresas, relacionadas entre s\u00ed, fueron proveedoras de la instalaci\u00f3n de sistema de audio, montaje y dem\u00e1s aditamentos en los eventos efectuados por el gobierno del expriista.<\/p>\n\n\n\n<p><strong>En el caso de Autica, tambi\u00e9n fue contratada para el suministro de medicamentos y otros insumos de orden sanitario contra la contingencia por Covid 19<\/strong>, pese a no ser su giro comercial.<\/p>\n\n\n\n<p>Tambi\u00e9n le fue cancelado el registro como proveedor de Consultor\u00eda Dwart, Corporativo Jubai y Grupo Construc Cyrpo.<\/p>\n\n\n\n<p>A Consultor\u00eda Dwart se le asocia con dos licitaciones con el gobierno estatal anterior por dos conceptos equivalentes a 9.8 millones de pesos: uno referente a servicios de inform\u00e1tica para el desarrollo de software, para el fomento del mercado interno y promoci\u00f3n del desarrollo econ\u00f3mico estatal, con el uso de tecnolog\u00eda digital, para la plataforma Consume Hidalgo, en sus versiones IOS y Android; adem\u00e1s, el desarrollo de una aplicaci\u00f3n para la Direcci\u00f3n General de Innovaci\u00f3n Tur\u00edstica.<\/p>\n\n\n\n<p><strong>El pasado 17 de agosto, la dependencia dio realiz\u00f3 la baja de otras 12 empresas en el padr\u00f3n por un periodo de 5 a\u00f1os.<\/strong><\/p>\n\n\n\n<p>Entonces se retir\u00f3 el registro de proveedor a Grupo Constructor Integral Cardavi, quien hizo trabajos en Epazoyucan y se le vincula a la Estafa Siniestra; Remaco Servicios Empresariales SA de CV, a la cual se le adjudicaron licitaciones por parte la Oficial\u00eda Mayor del en la pasada administraci\u00f3n; entre ellas, una por 18 millones de pesos para adquirir de insumos contra el Covid-19.<\/p>\n\n\n\n<p><strong>En el caso de Team Xao, forma parte de las tres empresas fantasmas ligadas a la Estafa Siniestra <\/strong>y de las cuales sus socios tienen \u00f3rdenes de aprehensi\u00f3n vigentes, mientras que a Corporativo para el Desarrollo de Negocios VAQPA se le asignaron 36 millones de pesos para servicios de consultor\u00eda y asesor\u00eda, presuntamente para generar un diagn\u00f3stico para la transici\u00f3n gubernamental del Poder Ejecutivo.<\/p>\n\n\n\n<p><strong>A ellos se sum\u00f3 Megaweb, Dise\u00f1o de Software, Mantenimiento y Renta de Equipos de C\u00f3mputos<\/strong>, empresa contratada para desarrollar el Programa de Resultados Electorales Preliminares (PREP) en las elecciones de alcaldes de 2020, mismo que no se llev\u00f3 a cabo cay\u00f3, situaci\u00f3n que caus\u00f3 la remoci\u00f3n de la entonces consejera presidenta del Instituto Estatal Electoral (IEEH) Guillermina V\u00e1zquez Ben\u00edtez por parte del Instituto Nacional Electoral (INE).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos empresas vinculadas con la adjudicaci\u00f3n de licitaciones para la realizaci\u00f3n de espect\u00e1culos, eventos y hasta la compra insumos y medicamentos para la emergencia del Covid-19 en el gobierno de&hellip; <\/p>\n","protected":false},"author":4,"featured_media":10781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/10780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=10780"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/10780\/revisions"}],"predecessor-version":[{"id":10782,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/10780\/revisions\/10782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/10781"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=10780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=10780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=10780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}