{"id":11598,"date":"2024-01-04T17:49:04","date_gmt":"2024-01-04T17:49:04","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=11598"},"modified":"2024-01-04T17:49:07","modified_gmt":"2024-01-04T17:49:07","slug":"encendido-del-arbol-y-espiritu-navideno-en-metztitlan-2","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/encendido-del-arbol-y-espiritu-navideno-en-metztitlan-2\/sociedad\/revista-acropolis\/","title":{"rendered":"Encendido del \u00c1rbol y Esp\u00edritu Navide\u00f1o en Metztitl\u00e1n"},"content":{"rendered":"\n<p>En una noche m\u00e1gica que reson\u00f3 con alegr\u00eda, el \u00e1rbol y esp\u00edritu navide\u00f1o iluminaron Metztitl\u00e1n con momentos especiales y recuerdos inolvidables.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"638\" height=\"667\" src=\"https:\/\/revistaacropolis.com\/wp-content\/uploads\/2024\/01\/metzti_2.jpeg\" alt=\"\" class=\"wp-image-11599\" srcset=\"https:\/\/revistaacropolis.com\/wp-content\/uploads\/2024\/01\/metzti_2.jpeg 638w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2024\/01\/metzti_2-287x300.jpeg 287w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2024\/01\/metzti_2-574x600.jpeg 574w\" sizes=\"(max-width: 638px) 100vw, 638px\" \/><\/figure>\n\n\n\n<p>El evento, lleno de actividades encantadoras, reuni\u00f3 a la comunidad en una celebraci\u00f3n vibrante.<\/p>\n\n\n\n<p>El jard\u00edn iluminado cautiv\u00f3 los corazones, proporcionando un escenario perfecto para capturar momentos m\u00e1gicos en el set fotogr\u00e1fico. Un divertido paseo en trenecito encant\u00f3 a chicos y grandes, mientras que el \u00e1rbol resplandec\u00eda con la esencia navide\u00f1a.<\/p>\n\n\n\n<p>El tradicional bazar navide\u00f1o, repleto de regalos y delicias, a\u00f1adi\u00f3 un toque festivo adicional.<\/p>\n\n\n\n<p>Este evento fue posible gracias al arduo trabajo en equipo de las diversas \u00e1reas del Ayuntamiento de Metztitl\u00e1n, bajo el liderazgo del Ing. Alfredo Morales Mora.<\/p>\n\n\n\n<p>La colaboraci\u00f3n entre el despacho del presidente y la asamblea fue esencial para hacer realidad esta celebraci\u00f3n tan especial.<\/p>\n\n\n\n<p>El ayuntamiento de Metztitl\u00e1n agradeci\u00f3 a la poblaci\u00f3n su entusiasta participaci\u00f3n, pues los habitantes contribuyen hacer de este tipo de eventos un momento \u00fanico, y se espera que la magia de la temporada fortalezca los lazos que hacen de Metztitl\u00e1n un lugar especial para vivir la Navidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una noche m\u00e1gica que reson\u00f3 con alegr\u00eda, el \u00e1rbol y esp\u00edritu navide\u00f1o iluminaron Metztitl\u00e1n con momentos especiales y recuerdos inolvidables. El evento, lleno de actividades encantadoras, reuni\u00f3 a la&hellip; <\/p>\n","protected":false},"author":4,"featured_media":11600,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[2092],"tags":[],"class_list":["post-11598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista-acropolis"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/11598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=11598"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/11598\/revisions"}],"predecessor-version":[{"id":11601,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/11598\/revisions\/11601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/11600"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=11598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=11598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=11598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}