{"id":11624,"date":"2024-01-05T22:16:05","date_gmt":"2024-01-05T22:16:05","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=11624"},"modified":"2024-01-05T22:16:17","modified_gmt":"2024-01-05T22:16:17","slug":"con-mesas-busca-morena-acuerdos-entre-aspirantes-a-municipios-cravioto","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/con-mesas-busca-morena-acuerdos-entre-aspirantes-a-municipios-cravioto\/politica\/","title":{"rendered":"Con mesas, busca Morena acuerdos entre aspirantes a municipios: Cravioto"},"content":{"rendered":"\n<p><strong>Previo a la aplicaci\u00f3n de encuestas para definir las candidaturas se buscar\u00e1 establecer acuerdos entre los liderazgos de los municipios y entre aspirantes para llegar a consensos y ahorrarse el proceso de la consulta, precis\u00f3 el senador C\u00e9sar Cravioto Romero, enlace del Comit\u00e9 Ejecutivo Nacional en Hidalgo.<\/strong><\/p>\n\n\n\n<p>En conferencia de prensa para confirmar la pr\u00f3xima visita de la precandidata a la presidencia Claudia Sheinbaum Pardo, prevista para el 14 de enero, dijo que en las pr\u00f3ximas semanas se buscar\u00e1 el acercamiento por medio de reuniones con los equipos los aspirantes.<\/p>\n\n\n\n<p>Confirm\u00f3 que instalar\u00e1n mesas de trabajo, municipio por municipio, en las que se buscar\u00e1n acuerdos en la mayor\u00eda de ellos y evitar divisi\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Vamos a buscar que haya acuerdo en el mayor n\u00famero de municipios posibles, vamos a buscar que haya integraci\u00f3n de equipos, para que no haya equipos que se sientan desplazados o para que no haya equipos que piensen que si ganan un municipio todo es para ese equipo. Tenemos la obligaci\u00f3n pol\u00edtica de generar consensos\u201d, afirm\u00f3 Cravioto Romero.<\/p><\/blockquote><\/figure>\n\n\n\n<p>Si logran consensos, asever\u00f3, Morena tendr\u00e1 la posibilidad de ganar los 84 municipios y con esto m\u00e1s de un mill\u00f3n de apoyos a la Sheinbaum Pardo, los 18 distritos locales, las senadur\u00edas y las siete curules de diputados federales.<\/p>\n\n\n\n<p>\u201cSi no nos ponemos de acuerdo, si empieza a haber diferencias, pues igual empieza a haber merma, pero la invitaci\u00f3n a todos los equipos del partido es que pongamos por delante el proyecto\u201d, dijo el senador, quien insisti\u00f3 en que convocar\u00e1n a los liderazgos de los municipios que quieren abanderar a Morena para ir en unidad y evitar rumores y especulaciones.<\/p>\n\n\n\n<p><strong>Aunque el partido tiene como m\u00e9todo la encuesta para designar a sus abanderados, Cravioto Romero subray\u00f3 que no es definitiva,<\/strong> pues si antes de realizarlas se realiza un acuerdo, se priorizar\u00e1 sobre la consulta.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>El partido tiene como m\u00e9todo la encuesta, pero si hay acuerdo, el acuerdo va sobre la encuesta, no estamos impedidos a buscar acuerdos (\u2026) la intenci\u00f3n de Morena es buscar el mayor n\u00famero de acuerdos en el mayor n\u00famero de municipios\u201d, afirm\u00f3.<\/p><\/blockquote><\/figure>\n\n\n\n<p>Adem\u00e1s, asegur\u00f3 que esto no transgrede a los m\u00e9todos del partido, pues en los casos donde no se den acuerdos se realizar\u00e1n la medicines u incluso otro m\u00e9todo de elecci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">QUEJAS<\/h3>\n\n\n\n<p>Respecto a los se\u00f1alamientos y quejas de la militancia y aspirantes sobre el proceso y la presuntas imposiciones de candidaturas, el enlace refiri\u00f3 que esto se debe a la expectativa de triunfo de las pr\u00f3ximas elecciones, de ah\u00ed que -dijo- la presi\u00f3n se encuentre sobre Morena y la dirigencia, contrario a lo de los otros partidos de la alianza opositora, asever\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La expectativa de triunfo esta en Morena, yo creo que ahorita las instalaciones del PRI est\u00e1n vac\u00edas, qui\u00e9n quiere hacer fila en el PRI, qui\u00e9n va a pelearse por una candidatura en el PRI, en el PAN, en el PRD, pues nadie, porque no hay expectativa de triunfo en aquel lado, la expectativa de triunfo est\u00e1 en este lado\u201d, sostuvo.<\/p><\/blockquote><\/figure>\n\n\n\n<p><strong>En tanto, dijo que la visita de Claudia Sheinbaum Pardo se relizar\u00e1 el pr\u00f3ximo domingo en los municipios de Tulancingo de Bravo y Mineral de la Reforma<\/strong>, aunque los horarios y sitios donde se reunir\u00e1 con la militancia como parte de los \u00faltimos actos de precampa\u00f1a siguen por confirmarse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previo a la aplicaci\u00f3n de encuestas para definir las candidaturas se buscar\u00e1 establecer acuerdos entre los liderazgos de los municipios y entre aspirantes para llegar a consensos y ahorrarse el&hellip; <\/p>\n","protected":false},"author":4,"featured_media":11625,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/11624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=11624"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/11624\/revisions"}],"predecessor-version":[{"id":11626,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/11624\/revisions\/11626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/11625"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=11624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=11624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=11624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}