{"id":12231,"date":"2024-01-30T05:58:30","date_gmt":"2024-01-30T05:58:30","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=12231"},"modified":"2024-01-30T06:12:44","modified_gmt":"2024-01-30T06:12:44","slug":"acusa-regidora-uso-electoral-con-cambio-en-aguinaldo-rosa-a-favor-de-presidenta-del-dif","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/acusa-regidora-uso-electoral-con-cambio-en-aguinaldo-rosa-a-favor-de-presidenta-del-dif\/politica\/","title":{"rendered":"Acusa regidora uso electoral con cambio en Aguinaldo Rosa a favor de presidenta del DIF"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Con la instauraci\u00f3n permanente del programa de Aguinaldo Rosa, el Sistema DIF de Mineral de la Reforma, a trav\u00e9s de su presidenta, <strong>Shadia Mart\u00ednez Lozada, ser\u00eda la encargada de su entrega, cuando ya confirm\u00f3 sus aspiraciones para contender por la alcald\u00eda de Mineral de la Reforma, acus\u00f3 la regidora morenista Hilda Miranda Miranda.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la sesi\u00f3n de Cabildo de este lunes,<strong> los ediles aprobaron por mayor\u00eda de votos el asentamiento del subsidio econ\u00f3mico de mil peso anuales para mujeres de 18 a 64 a\u00f1os de edad q<\/strong>ue viven bajo condiciones de pobreza moderada a extrema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la votaci\u00f3n se abstuvo Miranda Miranda, quien recrimin\u00f3 que para la discusi\u00f3n de las modificaciones al Aguinaldo Rosa no se convoc\u00f3 a la Comisi\u00f3n de Igualdad de G\u00e9nero, la cual preside, por lo cual -acus\u00f3- se violentaron sus derechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez, <strong>advirti\u00f3 que las modificaciones de ley que se plantearon para que este programa sea permanente implican que, seg\u00fan las reglas de operaci\u00f3n, ser\u00e1 la presidenta del DIF municipal la que entregue este recurso y ya no la Secretar\u00eda de Desarrollo Humano y Social.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bajo lo anterior, <strong>anunci\u00f3 que dar\u00eda vista a las autoridades electorales,<\/strong> al subrayar que Mart\u00ednez Lozada ya se encuentra inmersa en un proceso de selecci\u00f3n partidista para la contienda electoral de este 2024 para la alcald\u00eda de Mineral de la Reforma, la cual actualmente preside su esposo, Israel F\u00e9lix Soto.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"486\" src=\"https:\/\/revistaacropolis.com\/wp-content\/uploads\/2024\/01\/image-47.png\" alt=\"\" class=\"wp-image-12235\" srcset=\"https:\/\/revistaacropolis.com\/wp-content\/uploads\/2024\/01\/image-47.png 800w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2024\/01\/image-47-300x182.png 300w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2024\/01\/image-47-768x467.png 768w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2024\/01\/image-47-600x365.png 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Pero ustedes quieren que as\u00ed lo desarrolle la presidenta del DIF, cuando ella ya declaro que es aspirante entonces de un partido pol\u00edtico y a su vez pretende entregar estos programas sociales\u201d, acus\u00f3.<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el transcurso de la sesi\u00f3n, exigi\u00f3 una respuesta del por qu\u00e9 no se convoc\u00f3 a la comisi\u00f3n que preside.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El regidor <strong>Jahir Garc\u00eda Reyes afirm\u00f3 que no se convoc\u00f3 a la comisi\u00f3n de Igualdad de G\u00e9nero porque el punto de acuerdo que se turn\u00f3 <\/strong>al ayuntamiento fue solamente para la comisi\u00f3n de Gobernaci\u00f3n, Bando, Reglamentos y Circulares; Hacienda Municipal, Mejora Regulatoria; Ni\u00f1ez, Juventud y Deporte, y Participaci\u00f3n Ciudadana, pero no a la de la morenista, pese a que esta -asegur\u00f3- debi\u00f3 participar por el temas de igualdad de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La regidora, <strong>que tambi\u00e9n aspira a contender por el ayuntamiento<\/strong>, reiter\u00f3 que acudir\u00eda a las autoridades electorales para <strong>dar vista de lo que se interpreta como un uso de un programa social para la promoci\u00f3n electoral de la presidenta del DIF local.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta del DIF de Mineral de la Reforma se registr\u00f3 como aspirante a la candidatura de Mineral de la Reforma en el proceso interno de Morena, tras provenir del gobierno local y grupo pol\u00edtico que preside su esposo, quien apenas el a\u00f1o pasado renunci\u00f3 en el Partido Revolucionario Institucional (PRI), instituto que lo llev\u00f3 a ayuntamiento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">REPROCHA REGIDOR A FELIX<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, el regidor tricolor Francisco Javier Vargas Pacheco acus\u00f3 a F\u00e9lix Soto de saltarse a la representaci\u00f3n del Cabildo y autorizar puntos que no se analizaron en comisiones y se informaron como aprobados.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">O sea, no se vale, hay que tener un poco m\u00e1s de respeto por el Cabildo y por la sociedad\u201d, recrimin\u00f3.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez, <strong>culp\u00f3 al alcalde de los \u201cmalos servicios\u00bb y las condiciones por las cuales pasan los trabajadores de Servicios Municipales,<\/strong> al no contar con herramientas necesarias para las labores que desarrollan, lo que se traduce en que no otorgar los servicios de recolecci\u00f3n de basura o el mantenimiento \u00f3ptimo de parques y jardines en tiempo y en forma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA m\u00ed me da mucha tristeza ver que pasaremos a la historia como una de las peores administraciones de todos los tiempos\u201d, sostuvo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">DatoAcro<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>-La modificaci\u00f3n al Aguinaldo Rosa fue presentado el 21 de enero pasado por al presidenta del DIF cuando a\u00fan no era aprobada en el Cabildo. <\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la instauraci\u00f3n permanente del programa de Aguinaldo Rosa, el Sistema DIF de Mineral de la Reforma, a trav\u00e9s de su presidenta, Shadia Mart\u00ednez Lozada, ser\u00eda la encargada de su&hellip; <\/p>\n","protected":false},"author":14,"featured_media":12235,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[1],"tags":[592,2387],"class_list":["post-12231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-la-reforma","tag-shadia"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/12231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=12231"}],"version-history":[{"count":2,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/12231\/revisions"}],"predecessor-version":[{"id":12237,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/12231\/revisions\/12237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/12235"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=12231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=12231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=12231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}