{"id":13147,"date":"2024-03-04T16:25:41","date_gmt":"2024-03-04T22:25:41","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=13147"},"modified":"2024-03-04T16:25:53","modified_gmt":"2024-03-04T22:25:53","slug":"realizaran-en-molango-concurso-de-molenderas","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/realizaran-en-molango-concurso-de-molenderas\/sociedad\/comunicados\/","title":{"rendered":"\u00a0Realizar\u00e1n en Molango concurso de molenderas"},"content":{"rendered":"\n<p><strong><em>El s\u00e1bado 30 de marzo, a partir del mediod\u00eda, en la Laguna de Azteca, ubicada en el municipio de Molango de Escamilla, se llevar\u00e1 a cabo el Segundo Concurso de Molenderas de Metate, en el cual se espera la participaci\u00f3n de 15 a 20 competidores.<\/em><\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cEste evento, tiene como objetivo principal destacar y rescatar la rica tradici\u00f3n del metate, una pr\u00e1ctica ancestral que ha sido fundamental en la cultura local\u201d, resalt\u00f3 Miguel \u00c1ngel Ramos Camiro, organizador del evento.&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<p>En este certamen las y los participantes demostrar\u00e1n sus habilidades para moler nixtamal en su propio metate. El jurado, integrado por cinco expertos en el uso de dicha piedra y provenientes de diferentes municipios, garantizar\u00e1 imparcialidad y conocimiento especializado en la evaluaci\u00f3n.<\/p>\n\n\n\n<p>Quienes resulten ganadores de los tres primeros puestos ser\u00e1n recompensados con premios en efectivo: 2 mil pesos para el primer lugar, mil pesos para el segundo lugar y 500 pesos para el tercer puesto. Estos premios buscan reconocer y recompensar el esfuerzo y la habilidad de las y los concursantes.<\/p>\n\n\n\n<p>En esta edici\u00f3n se busca superar la marca del a\u00f1o pasado, en el que la ganadora estableci\u00f3 un r\u00e9cord de 8 minutos y medio.&nbsp;<\/p>\n\n\n\n<p>La entrada a este evento ser\u00e1 gratuita tanto para el p\u00fablico en general, como para las personas inscritas en dicho concurso, a fin de fomentar el aprecio por esta pr\u00e1ctica tradicional.<\/p>\n\n\n\n<p><strong><em>Se invita a la comunidad y a los interesados a unirse a esta experiencia \u00fanica, donde la esencia cultural se fusiona con la destreza individual, en un espacio para la celebraci\u00f3n y el reconocimiento de la herencia que el metate representa en Molango de Escamilla.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00e1bado 30 de marzo, a partir del mediod\u00eda, en la Laguna de Azteca, ubicada en el municipio de Molango de Escamilla, se llevar\u00e1 a cabo el Segundo Concurso de&hellip; <\/p>\n","protected":false},"author":16,"featured_media":13148,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[86],"tags":[89,284],"class_list":["post-13147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicados","tag-hidalgo","tag-turismo"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/13147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=13147"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/13147\/revisions"}],"predecessor-version":[{"id":13149,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/13147\/revisions\/13149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/13148"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=13147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=13147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=13147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}