{"id":14690,"date":"2024-04-24T21:16:21","date_gmt":"2024-04-25T03:16:21","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=14690"},"modified":"2024-04-24T21:16:43","modified_gmt":"2024-04-25T03:16:43","slug":"ceeh-a-viggiano-exige-disculpas-por-descalificar-encuesta-con-nuestros-impuestos-paga-su-campana","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/ceeh-a-viggiano-exige-disculpas-por-descalificar-encuesta-con-nuestros-impuestos-paga-su-campana\/politica\/","title":{"rendered":"CEEH a Viggiano: exige disculpas por descalificar encuesta; \u201cCon nuestros impuestos paga su campa\u00f1a\u201d \u00a0"},"content":{"rendered":"\n<p>Integrantes del Consejo Coordinador Empresarial de Hidalgo <strong>(CCEH) reprocharon \u201clos insultos y mentiras\u201d que, acusaron, emiti\u00f3 la candidata priista al Senado Carolina Viggiano Austria <\/strong>contra el presidente del ente, Alejandro S\u00e1nchez Ram\u00edrez, <strong>en reacci\u00f3n a la encuesta de preferencias electorales publicada por la agrupaci\u00f3n que da ventaja Morena<\/strong>.\u00a0 \u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Reprobamos en\u00e9rgicamente los insultos y mentiras vertidos por la candidata Carolina Viggiano, quien evidentemente carece de vocaci\u00f3n democr\u00e1tica y sorprendentemente mediante una campa\u00f1a de odio, diatriba y mentiras, busca nuevamente el voto de las y los hidalguenses\u00bb, se\u00f1al\u00f3 el consejo en un comunicado.\u00a0<\/p>\n<\/blockquote>\n\n\n\n<p>Ayer, la tambi\u00e9n secretaria general del Partido Revolucionario Institucional (PRI)<strong> critic\u00f3 el ejercicio de preferencias electoral encargado por el CCEH a la encuestadora Parametr\u00eda, que pone a Morena al frente <\/strong>para obtener el triunfo en la senadur\u00eda, todas las diputaciones federales y locales, as\u00ed como 10 municipios en los se aplic\u00f3 la medici\u00f3n.<\/p>\n\n\n\n<p>Asimismo, <strong>dijo que S\u00e1nchez Ram\u00edrez no muestra imparcialidad y asever\u00f3 que al ente gremial no tiene \u201cautoridad moral\u201d, le gusta \u201cel oficialismo\u201d, es \u201cquedabi\u00e9n\u201d<\/strong> y record\u00f3 que cuando el PRI gobernaba estaban \u00aba su favor\u201d.<\/p>\n\n\n\n<p>A trav\u00e9s de un comunicado, \u201clas presidentas y los presidentes de las c\u00e1maras y asociaciones empresariales\u201d que integran el CCEH<strong> manifestaron su solidaridad <\/strong>y \u201creconocimiento a la intachable labor\u201d que -dicen- realiza<strong> su dirigente.<\/strong><\/p>\n\n\n\n<p>El CCEH tambi\u00e9n<strong> recrimin\u00f3 a Viggiano Austria no haber reconocido su derrota en la elecci\u00f3n de 2022 <\/strong>y puso \u00e9nfasis en la baja aprobaci\u00f3n ciudadana hacia ella que muestra la encuesta elaborada por Parametr\u00eda a solicitud del ente empresarial.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Recordemos que en la pasada elecci\u00f3n del 2022, a pesar de que perdi\u00f3 por m\u00e1s de 30 puntos, nunca reconoci\u00f3 su derrota e impugn\u00f3 la decisi\u00f3n de la gran mayor\u00eda del pueblo hidalguense. Por todo ello no debe sorprenderle que en la encuesta realizada por Parametr\u00eda \u00a1tiene un 1% de aprobaci\u00f3n!\u201d, se\u00f1ala el comunicado.<\/p><\/blockquote><\/figure>\n\n\n\n<p>Asimismo, <strong>exigieron de la candidata priista una disculpa p\u00fablica a S\u00e1nchez Ramirez<\/strong> y que \u201cse conduzca con respeto\u201d.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>No pierda de vista que con nuestros impuestos estamos pagando su campa\u00f1a\u201d, agregaron.\u00a0<\/p><\/blockquote><\/figure>\n\n\n\n<p>\u201cEn el Consejo Coordinador Empresarial de Hidalgo, representamos a miles de peque\u00f1as, medianas y grandes empresas que generamos empleos y abonamos siempre al desarrollo de nuestro gran estado. La sociedad hidalguense merece representantes populares que est\u00e9n a la altura de los retos del futuro, gente honesta con valores y principios que dignifiquen la pol\u00edtica\u201d, a\u00f1ade el reproche de los empresarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Integrantes del Consejo Coordinador Empresarial de Hidalgo (CCEH) reprocharon \u201clos insultos y mentiras\u201d que, acusaron, emiti\u00f3 la candidata priista al Senado Carolina Viggiano Austria contra el presidente del ente, Alejandro&hellip; <\/p>\n","protected":false},"author":17,"featured_media":14691,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[1],"tags":[1453,1402],"class_list":["post-14690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-cceh","tag-viggiano"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/14690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=14690"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/14690\/revisions"}],"predecessor-version":[{"id":14692,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/14690\/revisions\/14692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/14691"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=14690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=14690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=14690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}