{"id":14921,"date":"2024-04-30T13:24:08","date_gmt":"2024-04-30T19:24:08","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=14921"},"modified":"2024-04-30T13:24:30","modified_gmt":"2024-04-30T19:24:30","slug":"hallan-sin-vida-a-hombre-en-situacion-de-calle-en-centro-de-pachuca","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/hallan-sin-vida-a-hombre-en-situacion-de-calle-en-centro-de-pachuca\/sociedad\/","title":{"rendered":"Hallan sin vida a hombre en situaci\u00f3n de calle en Centro de Pachuca"},"content":{"rendered":"\n<p>Un <strong>hombre en situaci\u00f3n de calle fue encontrado sin vida esta ma\u00f1ana en la colonia Centro de Pachuca<\/strong>, confirmaron autoridades municipales de Seguridad P\u00fablica.<\/p>\n\n\n\n<p>Por medio del n\u00famero de emergencias 911, usuario reporta a una persona indigente que est\u00e1 tirada boca abajo, con vestimenta pantal\u00f3n gris y chamarra caf\u00e9, <strong>en la calle Bartolom\u00e9 de Medina, entre Joaqu\u00edn Herrera y Miguel Lerdo de Tejada<\/strong>. Indicaron que aparentemente ya no cuenta con signos vitales.<\/p>\n\n\n\n<p>Al lugar arrib\u00f3 un elemento de la Secretar\u00eda de Seguridad P\u00fablica, Tr\u00e1nsito y Vialidad de Pachuca, <strong>quien verific\u00f3 la presencia del hombre, de aproximadamente 39 a\u00f1os<\/strong>, inconsciente, por lo cual solicit\u00f3 apoyo a la ambulancia de Cruz Roja.<\/p>\n\n\n\n<p>Posteriormente, <strong>los cuerpos de rescate confirma que el hombre en situaci\u00f3n de calle, de identidad desconocida, ya no presenta signos vitales.<\/strong><\/p>\n\n\n\n<p>El lugar qued\u00f3 resguardado en espera de las autoridades periciales de la Procuradur\u00eda General de Justicia de Hidalgo (PGJH).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un hombre en situaci\u00f3n de calle fue encontrado sin vida esta ma\u00f1ana en la colonia Centro de Pachuca, confirmaron autoridades municipales de Seguridad P\u00fablica. Por medio del n\u00famero de emergencias&hellip; <\/p>\n","protected":false},"author":16,"featured_media":14922,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[57],"tags":[89,2669,91],"class_list":["post-14921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad","tag-hidalgo","tag-noticias","tag-pachuca"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/14921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=14921"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/14921\/revisions"}],"predecessor-version":[{"id":14923,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/14921\/revisions\/14923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/14922"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=14921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=14921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=14921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}