{"id":16481,"date":"2024-06-10T20:18:03","date_gmt":"2024-06-11T02:18:03","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=16481"},"modified":"2024-06-10T20:18:15","modified_gmt":"2024-06-11T02:18:15","slug":"inicia-juicio-contra-exdirector-de-radio-y-television-de-hidalgo-por-peculado","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/inicia-juicio-contra-exdirector-de-radio-y-television-de-hidalgo-por-peculado\/politica\/","title":{"rendered":"Inicia juicio contra exdirector de Radio y Televisi\u00f3n de Hidalgo por peculado"},"content":{"rendered":"\n<p>Este lunes comenz\u00f3 el juicio oral contra e<strong>l director del Sistema de Radio y Televisi\u00f3n de Hidalgo (SRHT) en el sexenio del priista Francisco Olvera Ruiz, Sergio Islas Olvera, imputado por el delito de peculado<\/strong>, a m\u00e1s de nueve meses de su reaprehensi\u00f3n.<\/p>\n\n\n\n<p>De acuerdo con la imputaci\u00f3n, a cargo de la Fiscal\u00eda Especializada en Delitos de Corrupci\u00f3n de la Procuradur\u00eda General de Justicia de Hidalgo (PGJH), <strong>los hechos que se investigan ocurrieron durante el periodo en el que el imputado se desempe\u00f1\u00f3 como director general del ente, lapso en el que fueron celebrados contratos millonarios con un detrimento patrimonial a la instituci\u00f3n por 242 millones 492 mil 793 pesos<\/strong>, vinculado con la llamada Estafa Maestra y el uso de empresas fantasma.<\/p>\n\n\n\n<p>Durante la audiencia de este d\u00edas se desahogaron tres testimoniales, <strong>uno de ellos fue el de Christian\u00a0Guerrero Barrag\u00e1n (preso en el penal de Pachuca), tambi\u00e9n exdirector del SRHT<\/strong> y s<strong>u sucesor<\/strong>, quien estuvo en el cargo durante el sexenio del expriista y actual embajador de M\u00e9xico en el Reino de Noruega, Omar Fayad Meneses.<\/p>\n\n\n\n<p>En el periodo de Islas Olvera al frente de la dependencia, Guerrero Barrag\u00e1n -imputados por el delito de ejercicio indebido del servicio p\u00fablico por la p\u00e9rdida de 11 concesiones de radio durante su gesti\u00f3n (2016-2022)- era su subordinado, por lo que declar\u00f3 sobre los contratos se\u00f1alados.<\/p>\n\n\n\n<p>Esta <strong>es la primera audiencia de juicio contra el exfuncionario de Olvera Ruiz<\/strong>, relacionado con la firma de contratos con entes federales en el sexenio de Enrique Pe\u00f1a Nieto. El pr\u00f3ximo 19 de junio se llevar\u00e1 a cabo la siguiente.<\/p>\n\n\n\n<p>Islas Olvera fue reaprehendido en Tecamachalco, Estado de M\u00e9xico, por fuerza federales y estatales de ambas entidades el pasado 25 de agosto de 2023, fecha hasta la que estuvo sustra\u00eddo de la justicia por m\u00e1s de cuatro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">CULPABLE DE OTRO DELITO<\/h3>\n\n\n\n<p>Antes,\u00a0<strong>fue detenido el 19 de julio de 2017<\/strong>, acusado por el delito de negociaciones indebidas en agravio de la administraci\u00f3n p\u00fablica,\u00a0en la causa penal 84\/2017. En ella se le imput\u00f3 el desvi\u00f3 de m\u00e1s de 77 millones de pesos el ente.\u00a0<\/p>\n\n\n\n<p>En diciembre de ese a\u00f1o\u00a0fue condenado a dos a\u00f1os seis meses de prisi\u00f3n, a trav\u00e9s de un procedimiento abreviado en el que se declar\u00f3 culpable, pero lo enfrent\u00f3 en libertad.<strong>\u00a0Sin embargo, deb\u00eda reparar el agravio por 77 millones 919 mil 524 de pesos, pero no lo hizo.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este lunes comenz\u00f3 el juicio oral contra el director del Sistema de Radio y Televisi\u00f3n de Hidalgo (SRHT) en el sexenio del priista Francisco Olvera Ruiz, Sergio Islas Olvera, imputado&hellip; <\/p>\n","protected":false},"author":17,"featured_media":16482,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[1],"tags":[2713,1884,1189],"class_list":["post-16481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-cristiana-barragan","tag-sergio-islas","tag-srth"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/16481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=16481"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/16481\/revisions"}],"predecessor-version":[{"id":16483,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/16481\/revisions\/16483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/16482"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=16481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=16481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=16481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}