{"id":16556,"date":"2024-06-13T15:30:12","date_gmt":"2024-06-13T21:30:12","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=16556"},"modified":"2024-06-13T15:31:42","modified_gmt":"2024-06-13T21:31:42","slug":"anuncian-2da-edicion-de-encontre-escuela-hidalgo","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/anuncian-2da-edicion-de-encontre-escuela-hidalgo\/sociedad\/","title":{"rendered":"Anuncian 2da Edici\u00f3n de \u201cEncontr\u00e9 Escuela Hidalgo\u201d"},"content":{"rendered":"\n<p>Con el objetivo de que los padres de familia conozcan la diversidad educativa disponible en Hidalgo para sus hijos, el pr\u00f3ximo 14 de julio de 2024 se llevar\u00e1 a cabo la segunda edici\u00f3n de \u00abEncuentro Escuela Hidalgo\u00bb.<\/p>\n\n\n\n<p>Dicho evento se desarrollar\u00e1 en el Hotel La Joya de Pachuca, en un horario de 10:00 a 18:00 horas, <strong><em>con la intenci\u00f3n de que los padres de familia puedan conocer las diferentes escuelas para sus hijos. <\/em><\/strong>Adem\u00e1s, el personal docente, administrativo y los due\u00f1os de colegios tendr\u00e1n la oportunidad de intercambiar experiencias y planes de trabajo, fortaleciendo as\u00ed el sector educativo de la regi\u00f3n mediante el intercambio de conocimientos.<\/p>\n\n\n\n<p>Expertos en temas relevantes, de inter\u00e9s y actualidad estar\u00e1n presentes, brindando su experiencia, conocimientos e investigaci\u00f3n. Estos especialistas ofrecer\u00e1n valiosas perspectivas en diversas \u00e1reas educativas, asegurando que los asistentes aprovechen al m\u00e1ximo el ciclo de conferencias.<\/p>\n\n\n\n<p>Se abre el espacio para aquellas escuelas o colegios\u00a0 que deseen exponer sus servicios y acceder al Plan Expositor de Encontr\u00e9 Escuela. Este plan incluye espacios de 2mx3m con identificaci\u00f3n, una amplia difusi\u00f3n del evento para asegurar la presencia de clientes, un lugar preferencial en las siguientes ediciones y un costo por espacio de $4,500.00 + IVA, pagadero en dos exhibiciones. Adem\u00e1s, los expositores recibir\u00e1n gafetes de identificaci\u00f3n y boletos para las diferentes rifas a realizarse.<\/p>\n\n\n\n<p><strong><em>Participar\u00e1n escuelas de diferentes niveles acad\u00e9micos, mostrando la diversidad y riqueza de la oferta educativa de la regi\u00f3n.<\/em><\/strong> Esta segunda edici\u00f3n tiene como objetivo principal mostrar las diversas ofertas educativas existentes en Pachuca y Mineral de la Reforma para educaci\u00f3n privada. Adem\u00e1s, el evento ofrece beneficios directos a colaboradores, expositores y asistentes, promoviendo una mayor colaboraci\u00f3n y fortalecimiento del sistema educativo en Hidalgo.<\/p>\n\n\n\n<p>Un beneficio extra que encontrar\u00e1n los institutos en esta expo es la posibilidad de aumentar su visibilidad y networking. Adem\u00e1s, el objetivo para las escuelas participantes es que como m\u00ednimo obtengan una inscripci\u00f3n, tal y como sucedi\u00f3 en la edici\u00f3n pasada.<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n, puede contactarse al n\u00famero 7711279995 o seguirlos en la p\u00e1gina de Facebook: Expo Encontr\u00e9 Escuela.<\/p>\n\n\n\n<p>Expo Encontr\u00e9 Escuela promete ser una plataforma crucial para el desarrollo educativo de la regi\u00f3n, facilitando el aprendizaje continuo y la interacci\u00f3n entre todos los actores del sector educativo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el objetivo de que los padres de familia conozcan la diversidad educativa disponible en Hidalgo para sus hijos, el pr\u00f3ximo 14 de julio de 2024 se llevar\u00e1 a cabo&hellip; <\/p>\n","protected":false},"author":18,"featured_media":16559,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[57],"tags":[],"class_list":["post-16556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/16556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=16556"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/16556\/revisions"}],"predecessor-version":[{"id":16560,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/16556\/revisions\/16560"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/16559"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=16556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=16556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=16556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}