{"id":16698,"date":"2024-06-18T19:34:11","date_gmt":"2024-06-19T01:34:11","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=16698"},"modified":"2024-06-18T19:34:23","modified_gmt":"2024-06-19T01:34:23","slug":"diputados-aprueban-junta-de-gobierno-sin-compartir-morena-la-controlara-por-tres-anos","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/diputados-aprueban-junta-de-gobierno-sin-compartir-morena-la-controlara-por-tres-anos\/politica\/","title":{"rendered":"Diputados aprueban Junta de Gobierno sin compartir; Morena la controlar\u00e1 por tres a\u00f1os"},"content":{"rendered":"\n<p>Por unanimidad, <strong>27 diputados locales de todos los partidos aprobaron eliminar la rotaci\u00f3n de la presidencia de la Junta de Gobierno del Congreso local, por lo que a partir de la LXVI Legislatura Morena encabezar\u00e1 el ente rector por un periodo completo de tres a\u00f1os,<\/strong> al ser la bancada predominante, como ocurr\u00eda hasta 2018, cuando el Partido Revolucionario Institucional (PRI) era la primera fuerza.<\/p>\n\n\n\n<p>Con ello, la din\u00e1mica de que tres partidos y no solo uno controlara esa entidad del Legislativo de Hidalgo solamente dur\u00f3 seis a\u00f1os.<\/p>\n\n\n\n<p>El dictamen para <strong>modificar, reformar, adicionar y derogar diversas disposiciones de la Ley Org\u00e1nica del Poder Legislativo de la entidad se llev\u00f3 cabo un d\u00eda despu\u00e9s de que la dirigencia estatal de Morena, a cargo de Marco Antonio Rico Mercado,<\/strong> anunci\u00f3 que sus legisladores afectar\u00edan esta acci\u00f3n, que le da control de la Junta de Gobierno al partido con m\u00e1s curules.<\/p>\n\n\n\n<p>El paquete de reformas a esta ley que rige al Poder Legislativo tuvo como punto medular regresar el art\u00edculo 98 como se encontraba en 2018, <strong>cuando se modific\u00f3 antes de concluir la LXIII Legislatura para que la presidiera un a\u00f1o cada las tres fuerzas pol\u00edtica<\/strong> con mayor cantidad de diputados, ante la p\u00e9rdida de la mayor\u00eda que tendr\u00eda el PRI en la siguiente legislatura, la LXIV.<\/p>\n\n\n\n<p>En la exposici\u00f3n de motivos, <strong>los diputados Luis \u00c1ngel Tenorio Cruz, Erika Rodr\u00edguez Hern\u00e1ndez, Timoteo L\u00f3pez P\u00e9rez realizaron referencias a los diversos cambios a la legislaci\u00f3n,<\/strong> como la autor\u00eda de leyes y la equidad de g\u00e9nero en torno al Congreso.<\/p>\n\n\n\n<p>En tanto, la morenista Lisset Marcelino Tovar, quien vivi\u00f3 lo que denomin\u00f3 \u201cel albazo\u201d de 2018, rememor\u00f3 cuando el PRI y <strong>otros partidos reformaron el art\u00edculo del Ley Org\u00e1nica del Poder Legislativo para evitar que una nueva mayor\u00eda de alternancia<\/strong> tomara el mando por tres a\u00f1os en la LXIV legislatura.<\/p>\n\n\n\n<p>La legisladora <strong>pidi\u00f3 el voto a favor sus compa\u00f1eros para \u201crespetar el mandato\u201d que dio \u201cel pueblo de Hidalgo\u201d a Morena en las urnas, <\/strong>partido que junto a su aliado Nueva Alianza Hidalgo gan\u00f3 los 18 distritos por el principio de mayor\u00eda relativa en la jornada electoral del 2 de junio.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u201cC\u00f3mo olvidar aquel primero de julio de 2018 cuando el pueblo bueno, el pueblo hidalguense, decidi\u00f3 tomar las urnas y manifestar su respaldo al proyecto de transformaci\u00f3n que por primera vez en la historia de Hidalgo llegar\u00eda la primera bancada de alternancia con 17 diputados y diputados\u201d, extern\u00f3.<\/p><\/blockquote><\/figure>\n\n\n\n<p>Agradeci\u00f3 a la poblaci\u00f3n que <strong>\u201cpor tercera vez consecutiva\u201d le otorg\u00f3 \u201cla confianza al proyecto de transformaci\u00f3n\u201d, <\/strong>al tener Morena de nueva cuenta la mayor representaci\u00f3n en los curules locales, con 14 de Morena m\u00e1s cuatro de su aliando.<\/p>\n\n\n\n<p>Adem\u00e1s, c<strong>onsider\u00f3 \u201cjusta\u00bb la reforma empleada para reconocer al grupo mayoritario y que tenga \u201csin recatos, concesiones, golpes u otros amagues\u201d<\/strong> la presidencia de la Junta de Gobierno, desde donde se rige la vida interna del Congreso local<\/p>\n\n\n\n<p>\u201cEn 2018, recuerdo muy bien, nos opusimos con vehemencia, en un \u00faltimo atropello del entonces grupo pol\u00edtico dominante (PRI), pero en decadencia, u<strong>n paquete de reformas sin sentido que, entre otras cosas, planteaba la necesidad, imag\u00ednense ustedes, de una mayor\u00eda calificada para la reforma a las leyes org\u00e1nicas\u201d, <\/strong>se\u00f1al\u00f3 en alusi\u00f3n de la modificaci\u00f3n que puso un candado de 20 votos para blindar una modificaci\u00f3n que revirtiera la rotaci\u00f3n de la Junta de Gobierno, como ocurri\u00f3 hoy.<\/p>\n\n\n\n<p>Marcelino Tovar consider\u00f3 esa acci\u00f3n como \u201cun albazo legislativo\u201d del tricolor al ver perdido el poder para la siguiente legislatura.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Les entr\u00f3 a aquellas diputadas y diputados un \u00e1nimo democr\u00e1tico, transformador y modernizador de las instituciones del Estado. Ahora s\u00ed ped\u00edan respeto a las minor\u00edas y gritaban con supuesta visi\u00f3n autoritaria de nuestro movimiento\u201d, a\u00f1adi\u00f3.<\/p>\n<\/blockquote>\n\n\n\n<p>Al continuar <strong>con su mensaje record\u00f3 la represi\u00f3n de la que fueron objeto el pasado 31 de julio de 2018, a las afueras del recinto legislativo por parte de elementos de la polic\u00eda estatal a golpes y gas lacrim\u00f3geno, <\/strong>esto cuando trataban de impedir esta reforma que se aprob\u00f3 al vapor por los diputados de la LXIII legislatura y para la cual se tuvieron que ir bajo resguardo en veh\u00edculos oficiales de seguridad estatal para sesionar en la Universidad Tecnol\u00f3gica de Mineral de la Reforma.<\/p>\n\n\n\n<p>Tambi\u00e9n record\u00f3 la maniobra hecha en la LXIV Legislatura <strong>por el entonces presidente del PRI estatal y hoy miembro de la bancada de Morena, el diputado del Grupo Plural Independiente (GPI) Julio Manuel Valera Piedras, quien incit\u00f3 a huestes tricolores a tomar la tribuna en septiembre de 2018<\/strong> por el control del primer a\u00f1o de la Junta de Gobierno, ya con la reforma de la rotaci\u00f3n en funciones.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u201cC\u00f3mo cambian los tiempos y se alinean los intereses, soy una fiel creyente que el pasado de las personas no determina su presente y hoy podemos determinar esto y dar una gran muestra para aprobar grandes reformas para las y los hidalguenses\u201d, acentu\u00f3 la morenista al referir que \u201cno son iguales\u201d y el tiempo les dio la raz\u00f3n.<\/p><\/blockquote><\/figure>\n\n\n\n<p>\u201cSeamos garantes de respetar la voluntad popular\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>En la votaci\u00f3n a favor del dictamen, <strong>a los morenistas se sumaron sus nuevos integrantes provenientes del GPI, as\u00ed como los diputados independientes, mientras que los de Nueva Alianza Hidalgo, el Verde Ecologista (PVEM) y el Partido del Trabajo mantuvieron su postura de aliados,<\/strong> as\u00ed como el voto a favor Miguel \u00c1ngel Mart\u00ednez Gonz\u00e1lez, que a\u00fan ostenta la representaci\u00f3n perredista pese a haber sido candidato de Morena, y el de la diputada de Acci\u00f3n Nacional Silvia S\u00e1nchez Garc\u00eda.<\/p>\n\n\n\n<p><strong>LA REFORMA<\/strong><\/p>\n\n\n\n<p>Actualmente, el art\u00edculo 98 de la Ley Org\u00e1nica del Poder Legislativo estatal establece que <strong>\u201cLa Presidencia de la Junta ser\u00e1 ejercida, en forma alternada y para cada a\u00f1o legislativo, por los Coordinadores de los tres Grupos Legislativos<\/strong> que cuenten con el mayor n\u00famero de diputados\u201d.<\/p>\n\n\n\n<p>Con la reforma, que deber\u00e1 ser publicada en el Peri\u00f3dico Oficial del Estado de Hidalgo (POEH) <strong>para surtir efecto en la pr\u00f3xima legislatura, la repartici\u00f3n se anula y queda de la siguiente forma: \u201cLa Presidencia de la Junta ser\u00e1 ejercida por la Coordinadora o el Coordinador de aquel Grupo Legislativo <\/strong>que est\u00e9 integrado con el mayor n\u00famero de Diputadas y Diputados en el Congreso\u201d.<\/p>\n\n\n\n<p>Adem\u00e1s, <strong>se establece que la presidencia, la secretar\u00eda -que ahora ser\u00e1 represente la segunda fuerza pol\u00edtica<\/strong>&#8211; y las vocal\u00edas durar\u00e1n en su encargo los tres a\u00f1os correspondientes a la legislatura.<\/p>\n\n\n\n<p><strong>DatoAcro<\/strong><\/p>\n\n\n\n<p>-La reforma establece el concepto de legislador electo por la v\u00eda independiente o diputados que se declaran sin partido.<br>-A partir de la publicaci\u00f3n del decreto, no se podr\u00e1n conformar nuevos grupos legislativos, como ocurri\u00f3 con el GPI, con diputados que dejen un partido, pero s\u00ed tendr\u00e1n la posibilidad de integrarse a otra bancada.<\/p>\n\n\n\n<p>-Adem\u00e1s, la Unidad Institucional de G\u00e9nero del Congreso del Estado estar\u00e1n forzosamente presididas por una mujer, cuya designaci\u00f3n estar\u00e1 a cargo de quien presida la Junta de Gobierno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por unanimidad, 27 diputados locales de todos los partidos aprobaron eliminar la rotaci\u00f3n de la presidencia de la Junta de Gobierno del Congreso local, por lo que a partir de&hellip; <\/p>\n","protected":false},"author":14,"featured_media":16699,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[1],"tags":[663,50,2652,122],"class_list":["post-16698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-gobierno","tag-morena","tag-politica-3","tag-pri"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/16698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=16698"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/16698\/revisions"}],"predecessor-version":[{"id":16700,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/16698\/revisions\/16700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/16699"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=16698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=16698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=16698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}