{"id":1776,"date":"2023-03-13T20:59:12","date_gmt":"2023-03-13T20:59:12","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=1776"},"modified":"2023-03-13T20:59:53","modified_gmt":"2023-03-13T20:59:53","slug":"dice-banos-que-no-entrego-informacion-a-ediles-por-datos-confidenciales-niega-opacidad","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/dice-banos-que-no-entrego-informacion-a-ediles-por-datos-confidenciales-niega-opacidad\/politica\/","title":{"rendered":"Dice Ba\u00f1os que no entreg\u00f3 informaci\u00f3n a ediles por datos \u201cconfidenciales\u201d; niega opacidad"},"content":{"rendered":"\n<p>Luego de que Tribunal Electoral del Estado de Hidalgo (TEEH) determin\u00f3 que el alcalde Sergio Ba\u00f1os Rubio fue omiso y vulner\u00f3 el derecho de dos regidores priistas al no entregarles informaci\u00f3n solicitada sobre gasto p\u00fablico, el edil capitalino dijo que hay datos que son \u201cconfidenciales\u201d.<\/p>\n\n\n\n<p>\u201cLo que ellos indiquen nosotros lo vamos a acatar, pero hay mucha informaci\u00f3n que es confidencial, \u00f3sea que esos s\u00ed son datos personales que posiblemente se pueden dar hacia la vista (al tribunal), pero no lo podemos entregar porque, sino nosotros tambi\u00e9n incurrimos en una falta\u201d, dijo.<\/p>\n\n\n\n<p>De acuerdo con la resoluci\u00f3n del TEEH en el juicio ciudadano JDC-003\/2023, el municipio debe entregar a la asamble\u00edsta Liz Mar\u00eda P\u00e9rez Hern\u00e1ndez informaci\u00f3n p\u00fabica sobre gasto de gasolina en veh\u00edculos oficiales por parte de servidores p\u00fablicos, en refacciones y accesorios menores en equipo de transporte y maquinaria.<\/p>\n\n\n\n<p>En tanto, al edil Gerardo Martinez de la Cruz tiene que proporcionar una lista de bajas y despidos, padr\u00f3n de proveedores del municipio, adeudos del municipio y los procesos de contrataci\u00f3n v\u00eda licitaci\u00f3n, invitaci\u00f3n a tres y adjudicaci\u00f3n directa en la actual administraci\u00f3n.<\/p>\n\n\n\n<p>Ba\u00f1os Rubio insisti\u00f3 en que si el TEEH dice que esa informaci\u00f3n deber ser entregada y los solicitantes se hace \u201cresponsable\u201d de la misma, acatar\u00e1 la instrucci\u00f3n. Sin embargo, sostuvo que su gobierno a\u00fan no ha sido notificado sobre lo que \u201chace falta de entregar\u201d.<\/p>\n\n\n\n<p>Asimismo, el tambi\u00e9n empresario dijo que parte de la informaci\u00f3n requerida por los ediles de su partido se encuentra en el portal de transparencia de la alcald\u00eda.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cMuchos de esos datos se pueden consultar por esa \u00e1rea\u201d, indic\u00f3.<\/p>\n<\/blockquote>\n\n\n\n<p>Ba\u00f1os Rubio, a quien el TEEH se\u00f1al\u00f3 de trastocar los derechos pol\u00edticos electorales de los asamble\u00edstas en el ejercicio del cargo, afirm\u00f3 que el ayuntamiento \u201cno oculta nada\u201d y neg\u00f3 que se trate de un acto de opacidad.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u201cYa entregamos los datos que, desde nuestra \u00f3ptica, como te puedo decir, nosotros ya entregamos esa informaci\u00f3n que s\u00ed se puede entregar, ya se contest\u00f3 como se deber\u00eda de hacer, pero hay alguna otra que s\u00ed est\u00e1 protegida por la ley de datos personales\u201d.<\/p><cite>Insisti\u00f3.<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Dijo que dar\u00e1 \u201cvista\u201d y \u201cexplicar\u00e1\u201d al tribunal sobre los datos que considera confidenciales.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cVamos a atenderlo, pero vamos a explicar que hay datos que, posiblemente ellos, saben y conocen del tema, que son, pues, datos que hasta yo puedo incurrir en una falta (al darlos)\u201d, expuso.<\/p>\n<\/blockquote>\n\n\n\n<p>Asimismo, el alcalde del Partido Revolucionario Institucional (PRI) se deslind\u00f3 de \u201clo que hagan\u201d los regidores solicitantes con la informaci\u00f3n p\u00fablica que pidieron desde diciembre de 2022.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u201cLo vamos a entregar en tiempo y forma, porque hay cajas y cajas de informaci\u00f3n que se tienen que imprimir.\u201d.<\/p><cite>Expres\u00f3<\/cite><\/blockquote><\/figure>\n\n\n\n<div class=\"wp-block-query is-layout-flow wp-block-query-is-layout-flow\"><ul class=\"wp-block-post-template is-layout-flow wp-block-post-template-is-layout-flow\"><li class=\"wp-block-post post-23574 post type-post status-publish format-standard has-post-thumbnail hentry category-municipios-de-altura tag-pachuca tag-seguridad-publica-2\">\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/revistaacropolis.com\/index.php\/pachuca-blinda-sus-calles-con-operativos-nocturnos-y-vigilancia-permanente-en-colonias-y-zona-centro\/municipios-de-altura\/\" target=\"_self\"  ><img fetchpriority=\"high\" decoding=\"async\" width=\"2049\" height=\"1152\" src=\"https:\/\/revistaacropolis.com\/wp-content\/uploads\/2026\/05\/Portadas-Paginas-web-2026-05-12T154025.506.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Pachuca blinda sus calles con operativos nocturnos\u00a0y vigilancia permanente en colonias y zona centro\" style=\"object-fit:cover;\" srcset=\"https:\/\/revistaacropolis.com\/wp-content\/uploads\/2026\/05\/Portadas-Paginas-web-2026-05-12T154025.506.png 2049w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2026\/05\/Portadas-Paginas-web-2026-05-12T154025.506-300x169.png 300w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2026\/05\/Portadas-Paginas-web-2026-05-12T154025.506-1024x576.png 1024w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2026\/05\/Portadas-Paginas-web-2026-05-12T154025.506-768x432.png 768w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2026\/05\/Portadas-Paginas-web-2026-05-12T154025.506-1536x864.png 1536w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2026\/05\/Portadas-Paginas-web-2026-05-12T154025.506-600x337.png 600w\" sizes=\"(max-width: 2049px) 100vw, 2049px\" \/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\"><h2 class=\"wp-block-post-title has-small-font-size\"><a href=\"https:\/\/revistaacropolis.com\/index.php\/pachuca-blinda-sus-calles-con-operativos-nocturnos-y-vigilancia-permanente-en-colonias-y-zona-centro\/municipios-de-altura\/\" target=\"_self\" >Pachuca blinda sus calles con operativos nocturnos\u00a0y vigilancia permanente en colonias y zona centro<\/a><\/h2><\/div>\n<\/div>\n\n<\/li><li class=\"wp-block-post post-23561 post type-post status-publish format-standard has-post-thumbnail hentry category-municipios-de-altura tag-eduardo-medecigo-2 tag-hidalgo tag-los-tuzos tag-mineral-de-la-reforma tag-parque-la-comunidad tag-sam-esparza\">\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/revistaacropolis.com\/index.php\/mineral-de-la-reforma-inaugura-parque-la-comunidad-en-los-tuzos\/municipios-de-altura\/\" target=\"_self\"  ><img decoding=\"async\" width=\"2049\" height=\"1152\" src=\"https:\/\/revistaacropolis.com\/wp-content\/uploads\/2026\/05\/Portadas-Paginas-web-2026-05-12T130400.114.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Mineral de la Reforma inaugura Parque La Comunidad en Los Tuzos\" style=\"object-fit:cover;\" srcset=\"https:\/\/revistaacropolis.com\/wp-content\/uploads\/2026\/05\/Portadas-Paginas-web-2026-05-12T130400.114.png 2049w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2026\/05\/Portadas-Paginas-web-2026-05-12T130400.114-300x169.png 300w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2026\/05\/Portadas-Paginas-web-2026-05-12T130400.114-1024x576.png 1024w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2026\/05\/Portadas-Paginas-web-2026-05-12T130400.114-768x432.png 768w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2026\/05\/Portadas-Paginas-web-2026-05-12T130400.114-1536x864.png 1536w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2026\/05\/Portadas-Paginas-web-2026-05-12T130400.114-600x337.png 600w\" sizes=\"(max-width: 2049px) 100vw, 2049px\" \/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\"><h2 class=\"wp-block-post-title has-small-font-size\"><a href=\"https:\/\/revistaacropolis.com\/index.php\/mineral-de-la-reforma-inaugura-parque-la-comunidad-en-los-tuzos\/municipios-de-altura\/\" target=\"_self\" >Mineral de la Reforma inaugura Parque La Comunidad en Los Tuzos<\/a><\/h2><\/div>\n<\/div>\n\n<\/li><\/ul><\/div>\n\n\n\n<p><strong>DatoAcro<\/strong><\/p>\n\n\n\n<p>-En su resoluci\u00f3n, los magistrados electorales conminaron al presidente municipal de Pachuca para que en lo subsecuente \u201cevite poner en riesgo el derecho al ejercicio del cargo del actor o cualquier integrante del ayuntamiento\u201d.<\/p>\n\n\n\n<p>-El edil dijo que el ayuntamiento no tiene padr\u00f3n de proveedores, pues lo genera gobierno del estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de que Tribunal Electoral del Estado de Hidalgo (TEEH) determin\u00f3 que el alcalde Sergio Ba\u00f1os Rubio fue omiso y vulner\u00f3 el derecho de dos regidores priistas al no entregarles&hellip; <\/p>\n","protected":false},"author":4,"featured_media":1779,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[1],"tags":[459,91,136],"class_list":["post-1776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-informacion","tag-pachuca","tag-teeh"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/1776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=1776"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/1776\/revisions"}],"predecessor-version":[{"id":1778,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/1776\/revisions\/1778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/1779"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=1776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=1776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=1776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}