{"id":4701,"date":"2023-06-01T02:14:32","date_gmt":"2023-06-01T02:14:32","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=4701"},"modified":"2023-06-01T02:14:35","modified_gmt":"2023-06-01T02:14:35","slug":"pese-a-transa-edil-de-calnali-no-sera-separado-del-cargo-por-suspension-del-proceso-diputado","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/pese-a-transa-edil-de-calnali-no-sera-separado-del-cargo-por-suspension-del-proceso-diputado\/politica\/","title":{"rendered":"Pese a transa, edil de Calnali no ser\u00e1 separado del cargo por suspensi\u00f3n del proceso: diputado"},"content":{"rendered":"\n<p>Isaid Acosta T\u00e9llez, <strong>presidente municipal de Calnali, no ser\u00e1 separado del cargo mientras el proceso penal que enfrenta por el delito de negociaciones indebidas agravadas est\u00e9 suspendido<\/strong>, inform\u00f3 el diputado No\u00e9 Hern\u00e1ndez Bravo, <strong>presidente de la Comisi\u00f3n de Gobernaci\u00f3n del Congreso de Hidalgo.<\/strong><\/p>\n\n\n\n<p>Explic\u00f3 que, en el oficio que envi\u00f3 la jueza Janett Montiel Mendoza en respuesta a la petici\u00f3n del \u00f3rgano colegiado encargado de resolver el asunto,<strong> la funcionaria judicial indic\u00f3 que no se le impuso medida cautelar al alcalde emanado del extinto Partido Encuentro Social (PESH) y que, tras haber sido vinculado a proceso por las conductas delictivas que se le imputan, se le autoriz\u00f3 la suspensi\u00f3n condicional del proceso hasta el 11 de junio.<\/strong><\/p>\n\n\n\n<p>Por lo que, dijo, <strong>Acosta T\u00e9llez no ser\u00e1 separado del cargo durante la suspensi\u00f3n del proceso. Asimismo, indic\u00f3 que una vez que concluya el plazo le volver\u00e1n a solicitar a la jueza que informe si el imputado cumpli\u00f3 con la condici\u00f3n de la salida alterna al proceso penal de pagar una reparaci\u00f3n del da\u00f1o por 2 millones de pesos, <\/strong>junto con Miguel Jim\u00e9nez Espinosa, expresidente municipal de Calnali, y si la vinculaci\u00f3n a proceso sigue firme o si se sobresee la causa penal.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Para m\u00ed ya concluy\u00f3, para el Congreso ya concluy\u00f3 en base lo que la jueza me ordena. Continuar\u00eda si el 11 de julio la jueza dice: \u2018fallaste con todo lo que te orden\u00f3 que cumpliera, fallaste aqu\u00ed\u2019, entonces yo le pido que por favor me notifique si la vinculaci\u00f3n quedar\u00eda firme\u201d, mencion\u00f3 en entrevista con medios de comunicaci\u00f3n.<\/p><\/blockquote><\/figure>\n\n\n\n<p><strong>Hern\u00e1ndez Bravo hizo un llamado a los pobladores de Calnali, <\/strong>que en diversas ocasiones han protestado para pedir la destituci\u00f3n de Isaid Acosta desde que asumi\u00f3 el cargo (cuando estaba suspendido, debido a que la Contralor\u00eda municipal consider\u00f3 que cometi\u00f3 negligencia administrativa en la administraci\u00f3n de Jim\u00e9nez Espinosa, cuando se desempe\u00f1\u00f3 como secretario de Obras P\u00fablicas), <strong>a que tengan \u00abpaciencia\u00bb a lo que resuelva la jueza.<\/strong><\/p>\n\n\n\n<p>Por este asunto, <strong>Isaid Acosta y Miguel Jim\u00e9nez obtuvieron una salida alterna al proceso penal y deben pagar una reparaci\u00f3n del da\u00f1o por 2 millones de pesos en favor del municipio, <\/strong>medida que les fue impuesta durante la audiencia inicial en la que fueron vinculadas a proceso por el delito de negociaciones indebidas agravadas, en donde la defensa de los imputados plante\u00f3 una suspensi\u00f3n condicional del proceso de 6 meses.\u00a0<\/p>\n\n\n\n<p>Por ello, una vez que cumplan con las condiciones impuestas por la jueza de control, habr\u00eda una extinci\u00f3n de la acci\u00f3n penal y la causa se sobreseer\u00eda, por lo que los imputados no tendr\u00edan antecedente penal al no haber sido sentenciados, <strong>a pesar que son se\u00f1alados de haber otorgado diversos contratos de obra a una empresa constructora y realizaron compras discrecionales con una comercializadora de manera indebida, por un monto de 5 millones de pesos, durante el periodo del 5 de septiembre de 2016 al 4 de septiembre de 2020.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Isaid Acosta T\u00e9llez, presidente municipal de Calnali, no ser\u00e1 separado del cargo mientras el proceso penal que enfrenta por el delito de negociaciones indebidas agravadas est\u00e9 suspendido, inform\u00f3 el diputado&hellip; <\/p>\n","protected":false},"author":9,"featured_media":4702,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[1],"tags":[509,245,510],"class_list":["post-4701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-calnali","tag-congreso","tag-isaid-acosta"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/4701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=4701"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/4701\/revisions"}],"predecessor-version":[{"id":4703,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/4701\/revisions\/4703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/4702"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=4701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=4701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=4701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}