{"id":7631,"date":"2023-08-19T06:53:18","date_gmt":"2023-08-19T06:53:18","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=7631"},"modified":"2023-08-19T06:53:30","modified_gmt":"2023-08-19T06:53:30","slug":"expiden-ley-de-revocacion-de-mandato-en-hidalgo","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/expiden-ley-de-revocacion-de-mandato-en-hidalgo\/politica\/","title":{"rendered":"Expiden Ley de Revocaci\u00f3n de Mandato en Hidalgo"},"content":{"rendered":"\n<p>Con 60 art\u00edculos, <strong>diputados locales aprobaron\u00a0la expedici\u00f3n de la Ley de Revocaci\u00f3n de Mandato de Hidalgo, <\/strong>con la cual, a la mitad del periodo de gobiernos, los ciudadanos podr\u00e1n determinar si el titular del Poder Ejecutivo es removido del cargo. Con ello, el estado se convirti\u00f3 en la segunda entidad en contar con esta norma.<\/p>\n\n\n\n<p>De acuerdo con la ley, la petici\u00f3n <strong>proceder\u00e1 si re\u00fane al menos al 10 por ciento de las inscritas en la lista nominal de electores en la entidad.<\/strong><\/p>\n\n\n\n<p>El apoyo recabado deber\u00e1 proceder de por lo menos la mitad m\u00e1s uno de los municipios (43)\u00a0 y que representen\u00a0el 3 por ciento de la lista nominal de electores de cada uno de ellos.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-acropolis wp-block-embed-acropolis\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"bFmChmRebZ\"><a href=\"https:\/\/revistaacropolis.com\/index.php\/avalan-clausula-de-vida-eterna-a-partidos-satelite-podran-repartir-votos-en-candidaturas-comunes\/politica\/\">Avalan &#8220;cl\u00e1usula de vida eterna&#8221; a partidos sat\u00e9lite: podr\u00e1n repartir votos en candidaturas comunes<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abAvalan &#8220;cl\u00e1usula de vida eterna&#8221; a partidos sat\u00e9lite: podr\u00e1n repartir votos en candidaturas comunes\u00bb \u2014 ACR\u00d3POLIS\" src=\"https:\/\/revistaacropolis.com\/index.php\/avalan-clausula-de-vida-eterna-a-partidos-satelite-podran-repartir-votos-en-candidaturas-comunes\/politica\/embed\/#?secret=UDsDmTYera#?secret=bFmChmRebZ\" data-secret=\"bFmChmRebZ\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>La solicitud ciudadana de revocaci\u00f3n de mandato \u00fanicamente se podr\u00e1 realizar en una ocasi\u00f3n, ante el Instituto Estatal Electoral de Hidalgo (IEEH), <strong>durante los tres meses posteriores al tercer a\u00f1o de gobierno; es decir, entre el 6 septiembre y el 5 de diciembre de esa anualidad.<\/strong><\/p>\n\n\n\n<p>Por ello, se le otorgan atribuciones al IEEH para llevar a cabo la organizaci\u00f3n, desarrollo y c\u00f3mputo de la votaci\u00f3n en el ejercicio de revocaci\u00f3n de mandato. De cumplirse los requisitos, <strong>deber\u00e1 fijar\u00e1 fecha para la jornada de votaci\u00f3n, misma que se celebrar\u00e1 el domingo siguiente a los 90 d\u00edas posteriores a la emisi\u00f3n de la convocatoria.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>El Instituto garantizar\u00e1 la integraci\u00f3n de las mesas directivas de casilla para la jornada de revocaci\u00f3n de mandato, compuestas por personas ciudadanas hidalguenses a raz\u00f3n de una persona que funja como presidenta o presidente, una como secretaria o secretario, una como escrutadora o escrutador y otra como suplente general, en los t\u00e9rminos que establezca el C\u00f3digo Electoral\u201d, se\u00f1ala.\u00a0<\/p>\n<\/blockquote>\n\n\n\n<p>El d\u00eda de la jornada, los participante deber\u00e1n responder la pregunta en la boleta: <strong>\u201c\u00bfEst\u00e1s de acuerdo en que la gobernadora o gobernador (nombre) contin\u00fae en sus funciones?\u201d,<\/strong> en cuyo caso se considerar\u00e1n dos opciones de respuesta: S\u00ed o No.\u00a0<\/p>\n\n\n\n<p>Para que el resultado sea vinculante, <strong>se requiere por la participaci\u00f3n del 40 ciento de las personas inscritas en la lista nominal de electores<\/strong>, y que el No represente la mayor\u00eda absoluta.\u00a0<\/p>\n\n\n\n<p>Si los resultados de la jornada de votaci\u00f3n indican que procede la revocaci\u00f3n de mandato, <strong>el Titular del Poder Ejecutivo del estado se entender\u00e1 separada definitivamente del cargo<\/strong>, cuando el Instituto emita la declaratoria de revocaci\u00f3n. Posteriormente, el Congreso elegir\u00eda a quien termine lo que resta del periodo de gobierno.<\/p>\n\n\n\n<p>La norma podr\u00e1 se aplicada a partir de este sexenio (2022-2028) a cargo del morenista Julio Menchaca Salazar. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">DatoAcro<\/h3>\n\n\n\n<p><em>-La ley contempla la posibilidad de que\u00a0 los hidalguenses que se encuentren en el extranjero, as\u00ed como las personas est\u00e9n en prisi\u00f3n preventiva, puedan participar en este mecanismo.<\/em><\/p>\n\n\n\n<p><em>-Las autoridades estatales, de los municipios, los partidos pol\u00edticos, sindicatos o cualquier otro tipo de organizaci\u00f3n del sector p\u00fablico, social o privado, deber\u00e1n abstenerse de impedir u obstruir las actividades de recopilaci\u00f3n de las firmas de apoyo de las ciudadanas y los ciudadanos.<\/em><\/p>\n\n\n\n<p>&#8211; Los diputados tambi\u00e9n avalaron reformas al C\u00f3digo Electoral en materia de revocaci\u00f3n de mandato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con 60 art\u00edculos, diputados locales aprobaron\u00a0la expedici\u00f3n de la Ley de Revocaci\u00f3n de Mandato de Hidalgo, con la cual, a la mitad del periodo de gobiernos, los ciudadanos podr\u00e1n determinar&hellip; <\/p>\n","protected":false},"author":4,"featured_media":7634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[1],"tags":[89,93,1829],"class_list":["post-7631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-hidalgo","tag-menchaca","tag-revocacion-de-mandato"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/7631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=7631"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/7631\/revisions"}],"predecessor-version":[{"id":7635,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/7631\/revisions\/7635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/7634"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=7631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=7631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=7631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}