{"id":8597,"date":"2023-09-13T20:29:01","date_gmt":"2023-09-13T20:29:01","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=8597"},"modified":"2023-09-13T20:29:13","modified_gmt":"2023-09-13T20:29:13","slug":"compromiso-de-dialogo-y-accion-para-reducir-riesgos-de-inundaciones-en-tula-de-allende","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/compromiso-de-dialogo-y-accion-para-reducir-riesgos-de-inundaciones-en-tula-de-allende\/politica\/","title":{"rendered":"Compromiso de di\u00e1logo y acci\u00f3n para reducir riesgos de inundaciones en Tula de Allende"},"content":{"rendered":"\n<p>En respuesta a los desaf\u00edos recurrentes de inundaciones que han afectado a la comunidad<br>de Tula de Allende, el Gobierno Municipal, bajo el liderazgo del Presidente Municipal, M.C.<br>Mario Francisco Guzm\u00e1n, llev\u00f3 a cabo una reuni\u00f3n crucial en la Sala de Cabildo de la<br>Presidencia Municipal. Esta reuni\u00f3n cont\u00f3 con la participaci\u00f3n de representantes de la<br>Comisi\u00f3n Nacional del Agua (CONAGUA), el Director de Obras P\u00fablicas Municipales y<br>miembros activos de la comunidad de Todos Somos Tula<\/p>\n\n\n\n<p><br>La historia reciente de Tula de Allende, ha sido marcada por las dificultades ocasionadas por<br>inundaciones, que han afectado tanto a la poblaci\u00f3n como a las \u00e1reas urbanas de la<br>localidad. Para abordar esta problem\u00e1tica de manera integral y efectiva, se reconoce la<br>necesidad de establecer mecanismos de di\u00e1logo interinstitucional que involucren a las<br>autoridades de los tres niveles de gobierno, con la finalidad de integrar planes de acci\u00f3n a<br>corto, mediano y largo plazo.<\/p>\n\n\n\n<p><br>Durante la reuni\u00f3n, cada uno de los participantes present\u00f3 propuestas esenciales para<br>abordar la problem\u00e1tica derivada de las inundaciones. <\/p>\n\n\n\n<p>Estas propuestas incluyeron la solicitud de la presencia de las empresas involucradas en la problem\u00e1tica, el acuerdo de dar seguimiento a la situaci\u00f3n del drenaje sanitario en el Centro de Tula, la enfatizaci\u00f3n de la importancia de mantener una comunicaci\u00f3n constante entre CONAGUA, la Direcci\u00f3n de Obras P\u00fablicas y el Comit\u00e9 de Vecinos, la programaci\u00f3n de un recorrido por parte de<br>CONAGUA en la comunidad de San Marcos, para evaluar los da\u00f1os ocasionados por la<br>inundaci\u00f3n de 2021, la petici\u00f3n de que, una vez concluidos los trabajos en la zona c\u00e9ntrica<br>de Tula, las calles se dejen en buen estado, y la exigencia de seguimiento a la reforestaci\u00f3n<br>en las \u00e1reas afectadas.<\/p>\n\n\n\n<p><br>Tras un di\u00e1logo constructivo, se lleg\u00f3 a un acuerdo para llevar a cabo un recorrido el d\u00eda<br>jueves 14 de septiembre de 2023 a las 8 de la ma\u00f1ana en el socav\u00f3n ubicado en la calle<br>Leandro Valle, de la Col. Centro, con el prop\u00f3sito de evaluar los da\u00f1os ocasionados. Adem\u00e1s,<br>CONAGUA, se comprometi\u00f3 a proporcionar a la Direcci\u00f3n de Obras P\u00fablicas, un plan de<br>medidas de mitigaci\u00f3n para el revestimiento del R\u00edo Tula. Estos acuerdos representan un<br>paso significativo hacia la resoluci\u00f3n de los problemas en Tula de Allende y demuestran la<br>voluntad de trabajar en conjunto para el beneficio de la comunidad y el mejoramiento de<br>la calidad de vida de sus habitantes.<\/p>\n\n\n\n<p><br>Al respecto, el Presidente Municipal, M.C. Mario Francisco Guzm\u00e1n, reafirm\u00f3 su<br>compromiso de garantizar la seguridad de todos los habitantes de Tula de Allende,<br>prestando una atenci\u00f3n especial a los m\u00e1s vulnerables.<br>Estos acuerdos representan un paso significativo hacia la resoluci\u00f3n de los problemas que<br>enfrenta la ciudad y demuestran la voluntad inquebrantable de trabajar juntos en beneficio<br>de la comunidad y en la mejora constante de la calidad de vida de sus residentes.<br>Finalmente, todos los asistentes a esta mesa de trabajo, incluyendo los representantes de<br>CONAGUA, la comunidad de Todos Somos Tula y otros colaboradores comprometidos,<br>firmaron la minuta, reafirmando as\u00ed su dedicaci\u00f3n y compromiso con la comunidad de Tula<br>de Allende.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En respuesta a los desaf\u00edos recurrentes de inundaciones que han afectado a la comunidadde Tula de Allende, el Gobierno Municipal, bajo el liderazgo del Presidente Municipal, M.C.Mario Francisco Guzm\u00e1n, llev\u00f3&hellip; <\/p>\n","protected":false},"author":10,"featured_media":8599,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[86,1],"tags":[],"class_list":["post-8597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicados","category-politica"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/8597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=8597"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/8597\/revisions"}],"predecessor-version":[{"id":8600,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/8597\/revisions\/8600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/8599"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=8597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=8597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=8597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}