{"id":9989,"date":"2023-11-08T15:45:50","date_gmt":"2023-11-08T15:45:50","guid":{"rendered":"https:\/\/revistaacropolis.com\/?p=9989"},"modified":"2023-11-08T15:45:53","modified_gmt":"2023-11-08T15:45:53","slug":"exigen-regidores-que-pgjh-destrabe-denuncias-contra-alcaldesa-de-tepeapulco","status":"publish","type":"post","link":"https:\/\/revistaacropolis.com\/index.php\/exigen-regidores-que-pgjh-destrabe-denuncias-contra-alcaldesa-de-tepeapulco\/politica\/","title":{"rendered":"Exigen regidores que PGJH destrabe denuncias contra alcaldesa de Tepeapulco"},"content":{"rendered":"\n<p>Ante presuntas interferencias al interior de la Procuradur\u00eda General de Justicia de Hidalgo (PGJH) a favor de la alcaldesa Marisol Ortega P\u00e9rez, <strong>regidores del cabildo de Tepeapulco solicitaron la intervenci\u00f3n directa del encargado de despacho, Santiago Nieto Castillo, para destrabar las denuncias penales que ha interpuesto contra la presidenta municipal.<\/strong><\/p>\n\n\n\n<p>De acuerdo con los regidores Oscar P\u00e9rez Espinoza, Ren\u00e9 Miranda Pallares y Mar\u00eda Guadalupe Gabriela Miranda Pallares,<strong> hay seis carpetas de investigaci\u00f3n ante las instancias de la PGJH contra la edil de Grupo Universidad<\/strong>; sin embargo, ninguna de ellas sigue su cauce legal, acusaron.<\/p>\n\n\n\n<p>A decir de los quejosos,<strong> existe protecci\u00f3n para la presidenta municipal por parte de la Contralor\u00eda estatal, a trav\u00e9s del director general de Combate a la Impunidad, Jorge Eduardo Crespo Ram\u00edrez, y de la PGJH<\/strong>, v\u00eda Julia Granados Hern\u00e1ndez, subprocuradora de la Regi\u00f3n Poniente, lo que hace que los procesos no se agilicen.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p><strong>Se ha preciado de decir (la alcaldesa) que tiene conexiones tanto aqu\u00ed en procuradur\u00eda como tambi\u00e9n en contralor\u00eda, (\u2026) Jorge Crespo ha ido personalmente a revisar estas carpetas de investigaci\u00f3n<\/strong>, lo cual es un uso de facultades que no se le atribuye, y por otra parte la subprocuradora del \u00e1rea ha detenido estas carpetas de investigaci\u00f3n y tambi\u00e9n se ha apreciado ser amiga de la presidenta\u201d, asegur\u00f3 el abogado de los regidores, Alberto Calder\u00f3n.<\/p><\/blockquote><\/figure>\n\n\n\n<p>En el caso espec\u00edfico de la PGJH, <strong>los regidores piden que la subprocuradora se abstenga de intervenir o no conozca de estos asuntos<\/strong>, pues consideran que empantana las investigaciones.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"720\" height=\"1024\" src=\"https:\/\/revistaacropolis.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-08-at-9.02.29-AM.jpeg\" alt=\"\" class=\"wp-image-9991\" srcset=\"https:\/\/revistaacropolis.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-08-at-9.02.29-AM.jpeg 720w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-08-at-9.02.29-AM-211x300.jpeg 211w, https:\/\/revistaacropolis.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-08-at-9.02.29-AM-422x600.jpeg 422w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p>\u201c<strong>Por ello es que venimos a hablar con el se\u00f1or procurador para que se puedan hacer a un lado estas l\u00edneas o estas posibles l\u00edneas en favor de la presidenta y se act\u00fae conforme a derecho<\/strong>\u201d, puntualiz\u00f3 el defensor.<\/p>\n\n\n\n<p><strong>Contra Ortega L\u00f3pez pesan seis denuncias ante la PGJH<\/strong>, una ante la Fiscal\u00eda Especializada en Delitos de Corrupci\u00f3n bajo el expediente REGTEPH\/005\/2023 por presuntos hechos de corrupci\u00f3n con recurso extraordinario obtenido por la Secretar\u00eda de Finanzas P\u00fablicas de la entidad, se\u00f1ala la parte acusadora.<\/p>\n\n\n\n<p>En la segunda ante la misma fiscal\u00eda (carpeta REGTEPH\/004\/2023) <strong>denuncian la contrataci\u00f3n de servicios de salud y firma de convenios con instituciones privadas anuales con montos abiertos<\/strong>, que -se\u00f1alan- otorgan empleo a su hermano Oscar Gabriel Ortega L\u00f3pez.<\/p>\n\n\n\n<p>La tercera, que obra en la carpeta REGTEPH\/003\/2023, <strong>manifiesta una presunta responsabilidad administrativa por conflicto de inter\u00e9s por parte de Nancy Yasm\u00edn Ortega L\u00f3pez<\/strong>, hermana de la presidenta municipal de Tepeapulco.<\/p>\n\n\n\n<p>La cuarta (NUC: 12-2023-07797) refiere la <strong>posible constituci\u00f3n del delito de uso indebido de atribuciones en la adquisici\u00f3n de un terreno para el Banco Bienestar de Tepeapulco<\/strong>, mismo que compr\u00f3 a un cercano sin la autorizaci\u00f3n del Cabildo.<\/p>\n\n\n\n<p>Adem\u00e1s, ante el Ministerio P\u00fablico de la Regi\u00f3n Oriente en Ciudad Sahag\u00fan est\u00e1n las NUC: 03.2023-00707 y NUC: 03-2023-00713 <strong>por el se\u00f1alamiento de privaci\u00f3n de la libertad a asamble\u00edstas municipales por no aprobar la segunda modificaci\u00f3n del presupuesto<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Por eso nuestra insistencia ya no de pasar a la subprocuradur\u00eda, sino de pasar directamente con el procurador\u201d, precis\u00f3 la regidora de Morena Miranda Pallares<\/p><\/blockquote><\/figure>\n\n\n\n<p>Junto a estas denuncias<strong>, los regidores tambi\u00e9n acusaron atropellos en su contra<\/strong>, amenazas, agresiones f\u00edsicas, golpes y otro tipo de actos intimidatorios.<\/p>\n\n\n\n<p>Miranda Pallares dijo que en Tepeapulco no gobierna Morena, pese a ser el partido por el cual lleg\u00f3 la alcaldesa al ayuntamiento, sino que \u201cmanda Grupo Universidad\u201d.<\/p>\n\n\n\n<p>\u201cSon temas muy delicados en que nosotros a veces tocamos intereses del grupo que gobierno, porque no es Morena, ah\u00ed no gobierno Morena, ah\u00ed gobierna Grupo Universidad\u201d, asegur\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante presuntas interferencias al interior de la Procuradur\u00eda General de Justicia de Hidalgo (PGJH) a favor de la alcaldesa Marisol Ortega P\u00e9rez, regidores del cabildo de Tepeapulco solicitaron la intervenci\u00f3n&hellip; <\/p>\n","protected":false},"author":4,"featured_media":9990,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[1],"tags":[2228,2226,2227],"class_list":["post-9989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-denuncias-2","tag-regidores-2","tag-tepeapulco-2"],"_links":{"self":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/9989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/comments?post=9989"}],"version-history":[{"count":1,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/9989\/revisions"}],"predecessor-version":[{"id":9992,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/posts\/9989\/revisions\/9992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media\/9990"}],"wp:attachment":[{"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/media?parent=9989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/categories?post=9989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaacropolis.com\/index.php\/wp-json\/wp\/v2\/tags?post=9989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}